{"id":9907,"date":"2020-02-01T10:01:00","date_gmt":"2020-02-01T10:01:00","guid":{"rendered":"https:\/\/www.opensolar.com\/post\/news\/opensolar-und-plenti-starten-partnerschaft-um-australischen-hausbesitzern-den-zugang-zu-erneuerbaren-energien-zu-erleichtern\/"},"modified":"2020-02-01T10:01:00","modified_gmt":"2020-02-01T10:01:00","slug":"opensolar-und-plenti-starten-partnerschaft-um-australischen-hausbesitzern-den-zugang-zu-erneuerbaren-energien-zu-erleichtern","status":"publish","type":"news","link":"https:\/\/www.opensolar.com\/de\/post\/news\/opensolar-und-plenti-starten-partnerschaft-um-australischen-hausbesitzern-den-zugang-zu-erneuerbaren-energien-zu-erleichtern\/","title":{"rendered":"OpenSolar und Plenti starten Partnerschaft, um australischen Hausbesitzern den Zugang zu erneuerbaren Energien zu erleichtern"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<p>OpenSolar und Plenti haben heute eine aufregende neue Partnerschaft angek\u00fcndigt, die die Solarfinanzierung mit einer leistungsstarken Vertriebssoftware&#8230;<\/p>\n","protected":false},"template":"","class_list":["post-9907","news","type-news","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.6 (Yoast SEO v26.6) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>OpenSolar und Plenti starten Partnerschaft, um australischen Hausbesitzern den Zugang zu erneuerbaren Energien zu erleichtern | OpenSolar<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.opensolar.com\/de\/post\/news\/opensolar-und-plenti-starten-partnerschaft-um-australischen-hausbesitzern-den-zugang-zu-erneuerbaren-energien-zu-erleichtern\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"OpenSolar und Plenti starten Partnerschaft, um australischen Hausbesitzern den Zugang zu erneuerbaren Energien zu erleichtern\" \/>\n<meta property=\"og:description\" content=\"OpenSolar und Plenti haben heute eine aufregende neue Partnerschaft angek\u00fcndigt, die die Solarfinanzierung mit einer leistungsstarken Vertriebssoftware...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.opensolar.com\/de\/post\/news\/opensolar-und-plenti-starten-partnerschaft-um-australischen-hausbesitzern-den-zugang-zu-erneuerbaren-energien-zu-erleichtern\/\" \/>\n<meta property=\"og:site_name\" content=\"OpenSolar\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/OpenSolarGlobal\/\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/www.opensolar.com\/wp-content\/uploads\/2024\/07\/OpenSolar-logo-for-WP.png?fit=1200%2C675&quality=80&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"675\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@opensolar\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.opensolar.com\/de\/post\/news\/opensolar-und-plenti-starten-partnerschaft-um-australischen-hausbesitzern-den-zugang-zu-erneuerbaren-energien-zu-erleichtern\/\",\"url\":\"https:\/\/www.opensolar.com\/de\/post\/news\/opensolar-und-plenti-starten-partnerschaft-um-australischen-hausbesitzern-den-zugang-zu-erneuerbaren-energien-zu-erleichtern\/\",\"name\":\"OpenSolar und Plenti starten Partnerschaft, um australischen Hausbesitzern den Zugang zu erneuerbaren Energien zu erleichtern | OpenSolar\",\"isPartOf\":{\"@id\":\"https:\/\/www.opensolar.com\/de\/#website\"},\"datePublished\":\"2020-02-01T10:01:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.opensolar.com\/de\/post\/news\/opensolar-und-plenti-starten-partnerschaft-um-australischen-hausbesitzern-den-zugang-zu-erneuerbaren-energien-zu-erleichtern\/#breadcrumb\"},\"inLanguage\":\"de-DE\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.opensolar.com\/de\/post\/news\/opensolar-und-plenti-starten-partnerschaft-um-australischen-hausbesitzern-den-zugang-zu-erneuerbaren-energien-zu-erleichtern\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.opensolar.com\/de\/post\/news\/opensolar-und-plenti-starten-partnerschaft-um-australischen-hausbesitzern-den-zugang-zu-erneuerbaren-energien-zu-erleichtern\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.opensolar.com\/de\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"News\",\"item\":\"https:\/\/www.opensolar.com\/de\/post\/news\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"OpenSolar und Plenti starten Partnerschaft, um australischen Hausbesitzern den Zugang zu erneuerbaren Energien zu erleichtern\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.opensolar.com\/de\/#website\",\"url\":\"https:\/\/www.opensolar.com\/de\/\",\"name\":\"OpenSolar\",\"description\":\"Solar Design And Proposal Software\",\"publisher\":{\"@id\":\"https:\/\/www.opensolar.com\/de\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.opensolar.com\/de\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de-DE\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.opensolar.com\/de\/#organization\",\"name\":\"OpenSolar\",\"url\":\"https:\/\/www.opensolar.com\/de\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de-DE\",\"@id\":\"https:\/\/www.opensolar.com\/de\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.opensolar.com\/wp-content\/uploads\/2026\/04\/OpenSolar-Horizontal-Color.svg\",\"contentUrl\":\"https:\/\/www.opensolar.com\/wp-content\/uploads\/2026\/04\/OpenSolar-Horizontal-Color.svg\",\"caption\":\"OpenSolar\"},\"image\":{\"@id\":\"https:\/\/www.opensolar.com\/de\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/OpenSolarGlobal\/\",\"https:\/\/x.com\/opensolar\",\"https:\/\/www.instagram.com\/open.solar\/\",\"https:\/\/www.linkedin.com\/company\/14522819\",\"https:\/\/www.youtube.com\/channel\/UCw3mdQ_ilIq9ZrPpCa_VOnA\/videos\"],\"description\":\"The world's leading solar design and proposal software. Free of charge so you're free to grow.\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"OpenSolar und Plenti starten Partnerschaft, um australischen Hausbesitzern den Zugang zu erneuerbaren Energien zu erleichtern | OpenSolar","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.opensolar.com\/de\/post\/news\/opensolar-und-plenti-starten-partnerschaft-um-australischen-hausbesitzern-den-zugang-zu-erneuerbaren-energien-zu-erleichtern\/","og_locale":"de_DE","og_type":"article","og_title":"OpenSolar und Plenti starten Partnerschaft, um australischen Hausbesitzern den Zugang zu erneuerbaren Energien zu erleichtern","og_description":"OpenSolar und Plenti haben heute eine aufregende neue Partnerschaft angek\u00fcndigt, die die Solarfinanzierung mit einer leistungsstarken Vertriebssoftware...","og_url":"https:\/\/www.opensolar.com\/de\/post\/news\/opensolar-und-plenti-starten-partnerschaft-um-australischen-hausbesitzern-den-zugang-zu-erneuerbaren-energien-zu-erleichtern\/","og_site_name":"OpenSolar","article_publisher":"https:\/\/www.facebook.com\/OpenSolarGlobal\/","og_image":[{"width":1200,"height":675,"url":"https:\/\/i0.wp.com\/www.opensolar.com\/wp-content\/uploads\/2024\/07\/OpenSolar-logo-for-WP.png?fit=1200%2C675&quality=80&ssl=1","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_site":"@opensolar","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.opensolar.com\/de\/post\/news\/opensolar-und-plenti-starten-partnerschaft-um-australischen-hausbesitzern-den-zugang-zu-erneuerbaren-energien-zu-erleichtern\/","url":"https:\/\/www.opensolar.com\/de\/post\/news\/opensolar-und-plenti-starten-partnerschaft-um-australischen-hausbesitzern-den-zugang-zu-erneuerbaren-energien-zu-erleichtern\/","name":"OpenSolar und Plenti starten Partnerschaft, um australischen Hausbesitzern den Zugang zu erneuerbaren Energien zu erleichtern | OpenSolar","isPartOf":{"@id":"https:\/\/www.opensolar.com\/de\/#website"},"datePublished":"2020-02-01T10:01:00+00:00","breadcrumb":{"@id":"https:\/\/www.opensolar.com\/de\/post\/news\/opensolar-und-plenti-starten-partnerschaft-um-australischen-hausbesitzern-den-zugang-zu-erneuerbaren-energien-zu-erleichtern\/#breadcrumb"},"inLanguage":"de-DE","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.opensolar.com\/de\/post\/news\/opensolar-und-plenti-starten-partnerschaft-um-australischen-hausbesitzern-den-zugang-zu-erneuerbaren-energien-zu-erleichtern\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.opensolar.com\/de\/post\/news\/opensolar-und-plenti-starten-partnerschaft-um-australischen-hausbesitzern-den-zugang-zu-erneuerbaren-energien-zu-erleichtern\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.opensolar.com\/de\/"},{"@type":"ListItem","position":2,"name":"News","item":"https:\/\/www.opensolar.com\/de\/post\/news\/"},{"@type":"ListItem","position":3,"name":"OpenSolar und Plenti starten Partnerschaft, um australischen Hausbesitzern den Zugang zu erneuerbaren Energien zu erleichtern"}]},{"@type":"WebSite","@id":"https:\/\/www.opensolar.com\/de\/#website","url":"https:\/\/www.opensolar.com\/de\/","name":"OpenSolar","description":"Solar Design And Proposal Software","publisher":{"@id":"https:\/\/www.opensolar.com\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.opensolar.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de-DE"},{"@type":"Organization","@id":"https:\/\/www.opensolar.com\/de\/#organization","name":"OpenSolar","url":"https:\/\/www.opensolar.com\/de\/","logo":{"@type":"ImageObject","inLanguage":"de-DE","@id":"https:\/\/www.opensolar.com\/de\/#\/schema\/logo\/image\/","url":"https:\/\/www.opensolar.com\/wp-content\/uploads\/2026\/04\/OpenSolar-Horizontal-Color.svg","contentUrl":"https:\/\/www.opensolar.com\/wp-content\/uploads\/2026\/04\/OpenSolar-Horizontal-Color.svg","caption":"OpenSolar"},"image":{"@id":"https:\/\/www.opensolar.com\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/OpenSolarGlobal\/","https:\/\/x.com\/opensolar","https:\/\/www.instagram.com\/open.solar\/","https:\/\/www.linkedin.com\/company\/14522819","https:\/\/www.youtube.com\/channel\/UCw3mdQ_ilIq9ZrPpCa_VOnA\/videos"],"description":"The world's leading solar design and proposal software. Free of charge so you're free to grow."}]}},"_links":{"self":[{"href":"https:\/\/www.opensolar.com\/de\/wp-json\/wp\/v2\/news\/9907","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.opensolar.com\/de\/wp-json\/wp\/v2\/news"}],"about":[{"href":"https:\/\/www.opensolar.com\/de\/wp-json\/wp\/v2\/types\/news"}],"version-history":[{"count":0,"href":"https:\/\/www.opensolar.com\/de\/wp-json\/wp\/v2\/news\/9907\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.opensolar.com\/de\/wp-json\/wp\/v2\/media?parent=9907"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}